{"id":7940,"date":"2024-02-26T17:44:36","date_gmt":"2024-02-26T16:44:36","guid":{"rendered":"https:\/\/libertia-logistica.com\/servizio-groupage\/"},"modified":"2024-05-08T12:12:37","modified_gmt":"2024-05-08T10:12:37","slug":"servizio-groupage","status":"publish","type":"page","link":"https:\/\/libertia-logistica.com\/it\/servizio-groupage\/","title":{"rendered":"Servizio Groupage"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Header&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;90deg&#8221; background_color_gradient_stops=&#8221;rgba(63,58,51,0.5) 0%|rgba(63,58,51,0.5) 100%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/libertia-logistica.com\/wp-content\/uploads\/2024\/04\/Grupaje-sf.jpg&#8221; min_height=&#8221;400px&#8221; custom_padding=&#8221;3%||3%||false|false&#8221; locked=&#8221;off&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;1700px&#8221; custom_padding=&#8221;3%||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;4a211b2e-dfd1-4d56-8c79-1160e4ce5141&#8243; header_text_color=&#8221;#FFFFFF&#8221; header_2_font=&#8221;Raleway|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;3em&#8221; header_2_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;|||0px||&#8221; border_color_bottom=&#8221;RGBA(255,255,255,0)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>SERVIZIO<br \/>DI GRAFICA<\/h2>\n<p>[\/et_pb_text][et_pb_divider color=&#8221;#3B9F3B&#8221; divider_weight=&#8221;5px&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;75px&#8221; module_alignment=&#8221;left&#8221; custom_margin=&#8221;1%||0%||false|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;3%||3%||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;4px|||||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.22.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;4a211b2e-dfd1-4d56-8c79-1160e4ce5141&#8243; text_font=&#8221;Raleway||||||||&#8221; text_font_size=&#8221;19px&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_2_font=&#8221;Raleway|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#3F3A33&#8243; header_2_font_size=&#8221;3em&#8221; header_2_line_height=&#8221;35px&#8221; header_3_font=&#8221;Raleway|800||on|||||&#8221; header_3_text_align=&#8221;left&#8221; header_3_line_height=&#8221;26px&#8221; text_orientation=&#8221;justified&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;3%|0%|0.6%|0%|false|false&#8221; border_color_bottom=&#8221;RGBA(255,255,255,0)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Il groupage o trasporto break bulk \u00e8 una soluzione logistica che prevede il consolidamento di piccole partite di merci provenienti da aziende diverse che hanno una destinazione simile. Ottimizzando l&#8217;uso dello spazio all&#8217;interno del rimorchio e riducendo l&#8217;impatto ambientale grazie al minor numero di viaggi.<\/p>\n<p>In Libertia disponiamo di una potente infrastruttura che facilita la fornitura di questo servizio, caratterizzato da velocit\u00e0 e adattabilit\u00e0. Con flotte dotate delle pi\u00f9 recenti tecnologie per poter monitorare e controllare in modo efficiente le vostre merci in ogni momento.<\/p>\n<p>I nostri processi logistici sono svolti da specialisti, garantendo una gestione di qualit\u00e0 che si traduce in una riduzione dei costi, sia per i vettori che per i nostri clienti.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.22.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/libertia-logistica.com\/wp-content\/uploads\/2024\/04\/grupaje.png&#8221; alt=&#8221;grupaje Libertia&#8221; title_text=&#8221;grupaje&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||4px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;4a211b2e-dfd1-4d56-8c79-1160e4ce5141&#8243; header_text_color=&#8221;#FFFFFF&#8221; header_2_font=&#8221;Raleway|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#3B9F3B&#8221; header_2_font_size=&#8221;2em&#8221; header_2_line_height=&#8221;35px&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;|||0px||&#8221; border_color_bottom=&#8221;RGBA(255,255,255,0)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>VALORE AGGIUNTO<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; module_class=&#8221;et_pb_row&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||6px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/libertia-logistica.com\/wp-content\/uploads\/2024\/02\/Rapidez.png&#8221; alt=&#8221;Velocit\u00e0&#8221; title_text=&#8221;Velocit\u00e0&#8221; align=&#8221;center&#8221; module_class=&#8221;et_pb_column et_pb_column_1_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; height=&#8221;50px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text module_class=&#8221;et_pb_column et_pb_column_3_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;4a211b2e-dfd1-4d56-8c79-1160e4ce5141&#8243; text_font=&#8221;Raleway||||||||&#8221; text_font_size=&#8221;19px&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_2_font=&#8221;Raleway|700|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#3F3A33&#8243; header_2_font_size=&#8221;3em&#8221; header_2_line_height=&#8221;35px&#8221; header_3_font=&#8221;Raleway|600||on|||||&#8221; header_3_text_align=&#8221;left&#8221; header_3_line_height=&#8221;26px&#8221; text_orientation=&#8221;justified&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;3%|0%|4%|0%|false|false&#8221; header_3_text_align_tablet=&#8221;center&#8221; header_3_text_align_phone=&#8221;center&#8221; header_3_text_align_last_edited=&#8221;on|phone&#8221; border_color_bottom=&#8221;RGBA(255,255,255,0)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>VELOCIT\u00c0<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/libertia-logistica.com\/wp-content\/uploads\/2024\/02\/Adaptabilidad.png&#8221; alt=&#8221;Adattabilit\u00e0&#8221; title_text=&#8221;Adattabilit\u00e0&#8221; align=&#8221;center&#8221; module_class=&#8221;et_pb_column et_pb_column_1_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; height=&#8221;50px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text module_class=&#8221;et_pb_column et_pb_column_3_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;4a211b2e-dfd1-4d56-8c79-1160e4ce5141&#8243; text_font=&#8221;Raleway||||||||&#8221; text_font_size=&#8221;19px&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_2_font=&#8221;Raleway|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#3F3A33&#8243; header_2_font_size=&#8221;3em&#8221; header_2_line_height=&#8221;35px&#8221; header_3_font=&#8221;Raleway|600||on|||||&#8221; header_3_text_align=&#8221;left&#8221; header_3_line_height=&#8221;26px&#8221; text_orientation=&#8221;justified&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;3%|0%|4%|0%|false|false&#8221; header_3_text_align_tablet=&#8221;center&#8221; header_3_text_align_phone=&#8221;center&#8221; header_3_text_align_last_edited=&#8221;on|phone&#8221; border_color_bottom=&#8221;RGBA(255,255,255,0)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>ADATTABILIT\u00c0<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; module_class=&#8221;et_pb_row&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;3px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/libertia-logistica.com\/wp-content\/uploads\/2024\/02\/Control-eficiente.png&#8221; alt=&#8221;Controllo efficiente&#8221; title_text=&#8221;Controllo efficiente&#8221; align=&#8221;center&#8221; module_class=&#8221;et_pb_column et_pb_column_1_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; height=&#8221;50px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text module_class=&#8221;et_pb_column et_pb_column_3_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;4a211b2e-dfd1-4d56-8c79-1160e4ce5141&#8243; text_font=&#8221;Raleway||||||||&#8221; text_font_size=&#8221;19px&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_2_font=&#8221;Raleway|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#3F3A33&#8243; header_2_font_size=&#8221;3em&#8221; header_2_line_height=&#8221;35px&#8221; header_3_font=&#8221;Raleway|600||on|||||&#8221; header_3_line_height=&#8221;26px&#8221; text_orientation=&#8221;justified&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;3%|0%|4%|0%|false|false&#8221; header_3_text_align_tablet=&#8221;center&#8221; header_3_text_align_phone=&#8221;center&#8221; header_3_text_align_last_edited=&#8221;on|phone&#8221; border_color_bottom=&#8221;RGBA(255,255,255,0)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>CONTROLLO EFFICIENTE<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/libertia-logistica.com\/wp-content\/uploads\/2024\/02\/Reduccion-de-costes.png&#8221; alt=&#8221;Trattamento personalizzato&#8221; title_text=&#8221;Riduzione dei costi&#8221; align=&#8221;center&#8221; module_class=&#8221;et_pb_column et_pb_column_1_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; height=&#8221;50px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text module_class=&#8221;et_pb_column et_pb_column_3_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;4a211b2e-dfd1-4d56-8c79-1160e4ce5141&#8243; text_font=&#8221;Raleway||||||||&#8221; text_font_size=&#8221;19px&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_2_font=&#8221;Raleway|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#3F3A33&#8243; header_2_font_size=&#8221;3em&#8221; header_2_line_height=&#8221;35px&#8221; header_3_font=&#8221;Raleway|600||on|||||&#8221; header_3_line_height=&#8221;26px&#8221; text_orientation=&#8221;justified&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;3%|0%|4%|0%|false|false&#8221; header_3_text_align_tablet=&#8221;center&#8221; header_3_text_align_phone=&#8221;center&#8221; header_3_text_align_last_edited=&#8221;on|phone&#8221; border_color_bottom=&#8221;RGBA(255,255,255,0)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>RIDUZIONE DEI COSTI<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ededed&#8221; custom_padding=&#8221;3%||3%||false|false&#8221; global_colors_info=&#8221;{}&#8221; locked=&#8221;off&#8221;][et_pb_row _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||4px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;4a211b2e-dfd1-4d56-8c79-1160e4ce5141&#8243; header_text_color=&#8221;#FFFFFF&#8221; header_2_font=&#8221;Raleway|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#3F3A33&#8243; header_2_font_size=&#8221;3em&#8221; header_2_line_height=&#8221;35px&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;|||0px||&#8221; border_color_bottom=&#8221;RGBA(255,255,255,0)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Dove siamo?<\/h2>\n<p>[\/et_pb_text][et_pb_divider color=&#8221;#3B9F3B&#8221; divider_weight=&#8221;5px&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;5vw&#8221; max_width=&#8221;75px&#8221; module_alignment=&#8221;left&#8221; custom_margin=&#8221;1%||0%||false|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_5,1_5,3_5&#8243; make_equal=&#8221;on&#8221; disabled_on=&#8221;on|on|off&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|true&#8221; custom_css_free_form=&#8221;.et_pb_gutters3 .et_pb_column, .et_pb_gutters3.et_pb_row .et_pb_column {||    margin-right: 2%;||}&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;|0px|||false|false&#8221; custom_css_main_element=&#8221;width:7%!important;&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/libertia-logistica.com\/wp-content\/uploads\/2024\/03\/Ubicacion.png&#8221; alt=&#8221;Ubicaci\u00f3n Libertia&#8221; title_text=&#8221;Ubicaci\u00f3n&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; height=&#8221;4vw&#8221; custom_margin=&#8221;|2%|||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_image src=&#8221;https:\/\/libertia-logistica.com\/wp-content\/uploads\/2024\/03\/Telefono.png&#8221; alt=&#8221;Tel\u00e9fono Libertia&#8221; title_text=&#8221;Telefono&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; height=&#8221;4vw&#8221; custom_margin=&#8221;|2%|||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_image src=&#8221;https:\/\/libertia-logistica.com\/wp-content\/uploads\/2024\/03\/correo.png&#8221; alt=&#8221;Correo Libertia&#8221; title_text=&#8221;correo&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; height=&#8221;4vw&#8221; custom_margin=&#8221;|2%|||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;|0px|||false|false&#8221; custom_css_main_element=&#8221;width:41%!important;&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text module_class=&#8221;texto-responsive&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Raleway||||||||&#8221; text_font_size=&#8221;19px&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_2_font=&#8221;Raleway|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#3F3A33&#8243; header_2_font_size=&#8221;3em&#8221; header_2_line_height=&#8221;35px&#8221; header_3_font=&#8221;Raleway|800||on|||||&#8221; header_3_text_align=&#8221;left&#8221; header_3_line_height=&#8221;26px&#8221; text_orientation=&#8221;justified&#8221; height=&#8221;4vw&#8221; custom_margin=&#8221;|2%|3%||false|false&#8221; custom_padding=&#8221;|0px||0px|false|false&#8221; custom_css_main_element=&#8221;display: flex;||    flex-direction: row;||    align-items: center;||    justify-content: flex-start;&#8221; border_color_bottom=&#8221;RGBA(255,255,255,0)&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Pol. Ind. La Torrecilla, Avenida de la Torrecilla, 21<br \/>Centro Empresariale La Torrecilla 1\u00ba 11<br \/>14013, Cordoba<\/p>\n<p>[\/et_pb_text][et_pb_text module_class=&#8221;texto-responsive&#8221; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Raleway||||||||&#8221; text_font_size=&#8221;19px&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_2_font=&#8221;Raleway|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#3F3A33&#8243; header_2_font_size=&#8221;3em&#8221; header_2_line_height=&#8221;35px&#8221; header_3_font=&#8221;Raleway|800||on|||||&#8221; header_3_text_align=&#8221;left&#8221; header_3_line_height=&#8221;26px&#8221; text_orientation=&#8221;justified&#8221; height=&#8221;4vw&#8221; custom_margin=&#8221;|2%|3%||false|false&#8221; custom_padding=&#8221;|0px||0px|false|false&#8221; hover_enabled=&#8221;0&#8243; custom_css_main_element=&#8221;display: flex;||    flex-direction: row;||    align-items: center;||    justify-content: flex-start;&#8221; border_color_bottom=&#8221;RGBA(255,255,255,0)&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>957 088 960<\/p>\n<p>[\/et_pb_text][et_pb_text module_class=&#8221;texto-responsive&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Raleway||||||||&#8221; text_font_size=&#8221;19px&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_2_font=&#8221;Raleway|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#3F3A33&#8243; header_2_font_size=&#8221;3em&#8221; header_2_line_height=&#8221;35px&#8221; header_3_font=&#8221;Raleway|800||on|||||&#8221; header_3_text_align=&#8221;left&#8221; header_3_line_height=&#8221;26px&#8221; text_orientation=&#8221;justified&#8221; height=&#8221;4vw&#8221; custom_margin=&#8221;|2%|3%||false|false&#8221; custom_padding=&#8221;|0px||0px|false|false&#8221; custom_css_main_element=&#8221;display: flex;||    flex-direction: row;||    align-items: center;||    justify-content: flex-start;&#8221; border_color_bottom=&#8221;RGBA(255,255,255,0)&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>contacto@libertia-logistica.com<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;|0px|||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;0px|0px|0px|0px|true|true&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; global_colors_info=&#8221;{}&#8221;]<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d1905730.6799783276!2d-5.27964460580479!3d38.32754509011012!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0xd6cdf589bff614d%3A0xf6f892388255da6b!2sLibertia%20Soluciones%20Log%C3%ADsticas!5e0!3m2!1ses!2ses!4v1708713712851!5m2!1ses!2ses\" width=\"700\" height=\"350\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=&#8221;off|off|on&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/libertia-logistica.com\/wp-content\/uploads\/2024\/03\/Ubicacion.png&#8221; alt=&#8221;Ubicaci\u00f3n Libertia&#8221; title_text=&#8221;Ubicaci\u00f3n&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; height=&#8221;50px&#8221; custom_margin=&#8221;||3%||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#3F3A33&#8243; text_font_size=&#8221;19px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\">Pol. Ind. La Torrecilla, Avenida de la Torrecilla, 21<br \/>Centro Empresariale La Torrecilla 1\u00ba 11<br \/>14013, Cordoba<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/libertia-logistica.com\/wp-content\/uploads\/2024\/03\/Telefono.png&#8221; alt=&#8221;Tel\u00e9fono Libertia&#8221; title_text=&#8221;Telefono&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; height=&#8221;50px&#8221; custom_margin=&#8221;||3%||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#3F3A33&#8243; text_font_size=&#8221;19px&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: center;\">957 088 960<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/libertia-logistica.com\/wp-content\/uploads\/2024\/03\/correo.png&#8221; alt=&#8221;Correo Libertia&#8221; title_text=&#8221;correo&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; height=&#8221;50px&#8221; custom_margin=&#8221;||3%||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#3F3A33&#8243; text_font_size=&#8221;19px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\">contacto@libertia-logistica.com<\/p>\n<p>[\/et_pb_text][et_pb_code _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;0px|0px|0px|0px|true|true&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; global_colors_info=&#8221;{}&#8221;]<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d1905730.6799783276!2d-5.27964460580479!3d38.32754509011012!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0xd6cdf589bff614d%3A0xf6f892388255da6b!2sLibertia%20Soluciones%20Log%C3%ADsticas!5e0!3m2!1ses!2ses!4v1708713712851!5m2!1ses!2ses\" width=\"700\" height=\"350\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#3B9F3B&#8221; custom_padding=&#8221;0%||0%||true|false&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; module_class=&#8221;et_pb_row&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;0px|auto|0px|auto|false|false&#8221; custom_padding=&#8221;1%||1%||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/libertia-logistica.com\/wp-content\/uploads\/2024\/02\/reloj.png&#8221; title_text=&#8221;orologio&#8221; align=&#8221;center&#8221; module_class=&#8221;et_pb_column et_pb_column_1_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; height=&#8221;50px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text module_class=&#8221;et_pb_column et_pb_column_3_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;4a211b2e-dfd1-4d56-8c79-1160e4ce5141&#8243; text_font=&#8221;Raleway||||||||&#8221; text_font_size=&#8221;19px&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_2_font=&#8221;Raleway|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#3F3A33&#8243; header_2_font_size=&#8221;3em&#8221; header_2_line_height=&#8221;35px&#8221; header_3_font=&#8221;Raleway|600||on|||||&#8221; header_3_text_align=&#8221;left&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; header_3_line_height=&#8221;26px&#8221; text_orientation=&#8221;justified&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;3%|0%|0%|0%|false|false&#8221; header_3_text_align_tablet=&#8221;center&#8221; header_3_text_align_phone=&#8221;center&#8221; header_3_text_align_last_edited=&#8221;on|phone&#8221; border_color_bottom=&#8221;RGBA(255,255,255,0)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Consegna veloce<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/libertia-logistica.com\/wp-content\/uploads\/2024\/02\/seguridad.png&#8221; title_text=&#8221;sicurezza&#8221; align=&#8221;center&#8221; module_class=&#8221;et_pb_column et_pb_column_1_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; height=&#8221;50px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text module_class=&#8221;et_pb_column et_pb_column_3_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;4a211b2e-dfd1-4d56-8c79-1160e4ce5141&#8243; text_font=&#8221;Raleway||||||||&#8221; text_font_size=&#8221;19px&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_2_font=&#8221;Raleway|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#3F3A33&#8243; header_2_font_size=&#8221;3em&#8221; header_2_line_height=&#8221;35px&#8221; header_3_font=&#8221;Raleway|600||on|||||&#8221; header_3_text_align=&#8221;left&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; header_3_line_height=&#8221;26px&#8221; text_orientation=&#8221;justified&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;3%|0%|0%|0%|false|false&#8221; header_3_text_align_tablet=&#8221;center&#8221; header_3_text_align_phone=&#8221;center&#8221; header_3_text_align_last_edited=&#8221;on|phone&#8221; border_color_bottom=&#8221;RGBA(255,255,255,0)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>SICUREZZA<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/libertia-logistica.com\/wp-content\/uploads\/2024\/02\/soporte.png&#8221; title_text=&#8221;supporto&#8221; align=&#8221;center&#8221; module_class=&#8221;et_pb_column et_pb_column_1_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; height=&#8221;50px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text module_class=&#8221;et_pb_column et_pb_column_3_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;4a211b2e-dfd1-4d56-8c79-1160e4ce5141&#8243; text_font=&#8221;Raleway||||||||&#8221; text_font_size=&#8221;19px&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_2_font=&#8221;Raleway|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#3F3A33&#8243; header_2_font_size=&#8221;3em&#8221; header_2_line_height=&#8221;35px&#8221; header_3_font=&#8221;Raleway|600||on|||||&#8221; header_3_text_align=&#8221;left&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; header_3_line_height=&#8221;26px&#8221; text_orientation=&#8221;justified&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;3%|0%|0%|0%|false|false&#8221; header_3_text_align_tablet=&#8221;center&#8221; header_3_text_align_phone=&#8221;center&#8221; header_3_text_align_last_edited=&#8221;on|phone&#8221; border_color_bottom=&#8221;RGBA(255,255,255,0)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>SUPPORTO 24\/7<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SERVIZIODI GRAFICAIl groupage o trasporto break bulk \u00e8 una soluzione logistica che prevede il consolidamento di piccole partite di merci provenienti da aziende diverse che hanno una destinazione simile. Ottimizzando l&#8217;uso dello spazio all&#8217;interno del rimorchio e riducendo l&#8217;impatto ambientale grazie al minor numero di viaggi. In Libertia disponiamo di una potente infrastruttura che facilita [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","iawp_total_views":70,"footnotes":""},"class_list":["post-7940","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Servizio Groupage - Libertia Log\u00edstica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libertia-logistica.com\/it\/servizio-groupage\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servizio Groupage - Libertia Log\u00edstica\" \/>\n<meta property=\"og:description\" content=\"SERVIZIODI GRAFICAIl groupage o trasporto break bulk \u00e8 una soluzione logistica che prevede il consolidamento di piccole partite di merci provenienti da aziende diverse che hanno una destinazione simile. Ottimizzando l&#039;uso dello spazio all&#039;interno del rimorchio e riducendo l&#039;impatto ambientale grazie al minor numero di viaggi. In Libertia disponiamo di una potente infrastruttura che facilita [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libertia-logistica.com\/it\/servizio-groupage\/\" \/>\n<meta property=\"og:site_name\" content=\"Libertia Log\u00edstica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/LIBERTIA-Soluciones-Logsticas-SLU\/100067619059826\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-08T10:12:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libertia-logistica.com\\\/it\\\/servizio-groupage\\\/\",\"url\":\"https:\\\/\\\/libertia-logistica.com\\\/it\\\/servizio-groupage\\\/\",\"name\":\"Servizio Groupage - Libertia Log\u00edstica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libertia-logistica.com\\\/#website\"},\"datePublished\":\"2024-02-26T16:44:36+00:00\",\"dateModified\":\"2024-05-08T10:12:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libertia-logistica.com\\\/it\\\/servizio-groupage\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libertia-logistica.com\\\/it\\\/servizio-groupage\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libertia-logistica.com\\\/it\\\/servizio-groupage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/libertia-logistica.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servizio Groupage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libertia-logistica.com\\\/#website\",\"url\":\"https:\\\/\\\/libertia-logistica.com\\\/\",\"name\":\"Libertia Log\u00edstica\",\"description\":\"Las mejores soluciones log\u00edsticas para su transporte\",\"publisher\":{\"@id\":\"https:\\\/\\\/libertia-logistica.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libertia-logistica.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libertia-logistica.com\\\/#organization\",\"name\":\"Libertia Log\u00edstica\",\"url\":\"https:\\\/\\\/libertia-logistica.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/libertia-logistica.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libertia-logistica.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logo-libertia-1.png\",\"contentUrl\":\"https:\\\/\\\/libertia-logistica.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logo-libertia-1.png\",\"width\":975,\"height\":305,\"caption\":\"Libertia Log\u00edstica\"},\"image\":{\"@id\":\"https:\\\/\\\/libertia-logistica.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/LIBERTIA-Soluciones-Logsticas-SLU\\\/100067619059826\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/libertia-soluciones-logisticas\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Servizio Groupage - Libertia Log\u00edstica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libertia-logistica.com\/it\/servizio-groupage\/","og_locale":"it_IT","og_type":"article","og_title":"Servizio Groupage - Libertia Log\u00edstica","og_description":"SERVIZIODI GRAFICAIl groupage o trasporto break bulk \u00e8 una soluzione logistica che prevede il consolidamento di piccole partite di merci provenienti da aziende diverse che hanno una destinazione simile. Ottimizzando l'uso dello spazio all'interno del rimorchio e riducendo l'impatto ambientale grazie al minor numero di viaggi. In Libertia disponiamo di una potente infrastruttura che facilita [&hellip;]","og_url":"https:\/\/libertia-logistica.com\/it\/servizio-groupage\/","og_site_name":"Libertia Log\u00edstica","article_publisher":"https:\/\/www.facebook.com\/people\/LIBERTIA-Soluciones-Logsticas-SLU\/100067619059826\/","article_modified_time":"2024-05-08T10:12:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"14 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libertia-logistica.com\/it\/servizio-groupage\/","url":"https:\/\/libertia-logistica.com\/it\/servizio-groupage\/","name":"Servizio Groupage - Libertia Log\u00edstica","isPartOf":{"@id":"https:\/\/libertia-logistica.com\/#website"},"datePublished":"2024-02-26T16:44:36+00:00","dateModified":"2024-05-08T10:12:37+00:00","breadcrumb":{"@id":"https:\/\/libertia-logistica.com\/it\/servizio-groupage\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libertia-logistica.com\/it\/servizio-groupage\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/libertia-logistica.com\/it\/servizio-groupage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/libertia-logistica.com\/it\/"},{"@type":"ListItem","position":2,"name":"Servizio Groupage"}]},{"@type":"WebSite","@id":"https:\/\/libertia-logistica.com\/#website","url":"https:\/\/libertia-logistica.com\/","name":"Libertia Log\u00edstica","description":"Las mejores soluciones log\u00edsticas para su transporte","publisher":{"@id":"https:\/\/libertia-logistica.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libertia-logistica.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/libertia-logistica.com\/#organization","name":"Libertia Log\u00edstica","url":"https:\/\/libertia-logistica.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/libertia-logistica.com\/#\/schema\/logo\/image\/","url":"https:\/\/libertia-logistica.com\/wp-content\/uploads\/2024\/02\/Logo-libertia-1.png","contentUrl":"https:\/\/libertia-logistica.com\/wp-content\/uploads\/2024\/02\/Logo-libertia-1.png","width":975,"height":305,"caption":"Libertia Log\u00edstica"},"image":{"@id":"https:\/\/libertia-logistica.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/LIBERTIA-Soluciones-Logsticas-SLU\/100067619059826\/","https:\/\/es.linkedin.com\/company\/libertia-soluciones-logisticas"]}]}},"_links":{"self":[{"href":"https:\/\/libertia-logistica.com\/it\/wp-json\/wp\/v2\/pages\/7940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libertia-logistica.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/libertia-logistica.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/libertia-logistica.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/libertia-logistica.com\/it\/wp-json\/wp\/v2\/comments?post=7940"}],"version-history":[{"count":6,"href":"https:\/\/libertia-logistica.com\/it\/wp-json\/wp\/v2\/pages\/7940\/revisions"}],"predecessor-version":[{"id":9374,"href":"https:\/\/libertia-logistica.com\/it\/wp-json\/wp\/v2\/pages\/7940\/revisions\/9374"}],"wp:attachment":[{"href":"https:\/\/libertia-logistica.com\/it\/wp-json\/wp\/v2\/media?parent=7940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}